{"id":4,"count":11,"description":"Il corpo umano \u00e8 stato progettato per resistere a un'infinit\u00e0 di cambiamenti e attacchi portati dall'ambiente circostante. Il segreto di una buona salute sta nel riuscire ad adattarsi alle mutevoli sollecitazioni dell'organismo.","link":"https:\/\/www.thesixtyone.com\/it\/salute\/","name":"Salute","slug":"salute","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.thesixtyone.com\/it\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thesixtyone.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.thesixtyone.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.thesixtyone.com\/it\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}